{"id":5579,"date":"2026-01-12T14:16:30","date_gmt":"2026-01-12T06:16:30","guid":{"rendered":"https:\/\/bhess.jpm.gov.my\/?p=5579"},"modified":"2026-01-20T14:16:49","modified_gmt":"2026-01-20T06:16:49","slug":"kunjungan-hormat-kepada-tuan-yang-terutama-yang-di-pertua-negeri-sarawak-tun-pehin-sri-dr-haji-wan-junaidi-tuanku-jaafar","status":"publish","type":"post","link":"https:\/\/bhess.jpm.gov.my\/index.php\/kunjungan-hormat-kepada-tuan-yang-terutama-yang-di-pertua-negeri-sarawak-tun-pehin-sri-dr-haji-wan-junaidi-tuanku-jaafar\/","title":{"rendered":"Kunjungan hormat kepada Tuan Yang Terutama Yang di-Pertua Negeri Sarawak, Tun Pehin Sri Dr. Haji Wan Junaidi Tuanku Jaafar"},"content":{"rendered":"\n<div class=\"wp-block-envira-envira-gallery\"><div id=\"envira-gallery-wrap-5570\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"150\" data-gallery-theme=\"normal\" id=\"envira-gallery-5570\" class=\"envira-gallery-public envira-gallery-justified-public envira-gallery-0-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"0\"><div id=\"envira-gallery-item-5571\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833208\" data-envira-caption=\"6302983250300833208\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5571\" class=\"envira-gallery-image envira-gallery-image-1 envira-normal envira-lazy\" data-envira-index=\"1\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5571\" data-envira-caption=\"6302983250300833208\" alt=\"\" title=\"6302983250300833208\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5572\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833207\" data-envira-caption=\"6302983250300833207\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5572\" class=\"envira-gallery-image envira-gallery-image-2 envira-normal envira-lazy\" data-envira-index=\"2\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5572\" data-envira-caption=\"6302983250300833207\" alt=\"\" title=\"6302983250300833207\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5573\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833206\" data-envira-caption=\"6302983250300833206\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5573\" class=\"envira-gallery-image envira-gallery-image-3 envira-normal envira-lazy\" data-envira-index=\"3\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5573\" data-envira-caption=\"6302983250300833206\" alt=\"\" title=\"6302983250300833206\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5574\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833205\" data-envira-caption=\"6302983250300833205\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5574\" class=\"envira-gallery-image envira-gallery-image-4 envira-normal envira-lazy\" data-envira-index=\"4\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5574\" data-envira-caption=\"6302983250300833205\" alt=\"\" title=\"6302983250300833205\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5575\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833204\" data-envira-caption=\"6302983250300833204\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5575\" class=\"envira-gallery-image envira-gallery-image-5 envira-normal envira-lazy\" data-envira-index=\"5\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5575\" data-envira-caption=\"6302983250300833204\" alt=\"\" title=\"6302983250300833204\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5576\" class=\"envira-gallery-item enviratope-item envira-gallery-item-6 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833203\" data-envira-caption=\"6302983250300833203\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5576\" class=\"envira-gallery-image envira-gallery-image-6 envira-normal envira-lazy\" data-envira-index=\"6\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5576\" data-envira-caption=\"6302983250300833203\" alt=\"\" title=\"6302983250300833203\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5577\" class=\"envira-gallery-item enviratope-item envira-gallery-item-7 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833202\" data-envira-caption=\"6302983250300833202\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5577\" class=\"envira-gallery-image envira-gallery-image-7 envira-normal envira-lazy\" data-envira-index=\"7\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5577\" data-envira-caption=\"6302983250300833202\" alt=\"\" title=\"6302983250300833202\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><div id=\"envira-gallery-item-5578\" class=\"envira-gallery-item enviratope-item envira-gallery-item-8 envira-lazy-load\" style=\"padding-left: 1px; padding-bottom: 1px; padding-right: 1px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201.jpg\" class=\"envira-gallery-5570 envira-gallery-link\" rel=\"enviragallery5570\" title=\"6302983250300833201\" data-envira-caption=\"6302983250300833201\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><img decoding=\"async\" id=\"envira-gallery-image-5578\" class=\"envira-gallery-image envira-gallery-image-8 envira-normal envira-lazy\" data-envira-index=\"8\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201-1024x683-640x480.jpg\" data-envira-src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201-1024x683-640x480.jpg\" data-envira-gallery-id=\"5570\" data-envira-item-id=\"5578\" data-envira-caption=\"6302983250300833201\" alt=\"\" title=\"6302983250300833201\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201-1024x683-640x480.jpg 400w,https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201-1024x683-640x480.jpg 2x\" data-envira-width=\"300\" data-envira-height=\"200\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-safe-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833208.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833206.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833205.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833204.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833203.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833202.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833201.jpg\" alt=\"\" \/><\/noscript><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":5572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1080","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[74,75],"tags":[],"class_list":["post-5579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktiviti-2026","category-aktiviti-utama-26"],"modified_by":"adminbhess","rttpg_featured_image_url":{"full":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"landscape":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"portraits":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"thumbnail":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-150x150.jpg",150,150,true],"medium":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-300x200.jpg",300,200,true],"large":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"2048x2048":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"et-pb-post-main-image":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-400x250.jpg",400,250,true],"et-pb-post-main-image-fullwidth":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1080x675.jpg",1080,675,true],"et-pb-portfolio-image":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-400x284.jpg",400,284,true],"et-pb-portfolio-module-image":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-510x382.jpg",510,382,true],"et-pb-portfolio-image-single":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1080x720.jpg",1080,720,true],"et-pb-gallery-module-image-portrait":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-400x516.jpg",400,516,true],"et-pb-post-main-image-fullwidth-large":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207.jpg",1440,960,false],"et-pb-image--responsive--desktop":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-1280x853.jpg",1080,720,true],"et-pb-image--responsive--tablet":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-980x653.jpg",827,551,true],"et-pb-image--responsive--phone":["https:\/\/bhess.jpm.gov.my\/wp-content\/uploads\/2026\/01\/6302983250300833207-480x320.jpg",405,270,true]},"rttpg_author":{"display_name":"adminbhess","author_link":"https:\/\/bhess.jpm.gov.my\/index.php\/author\/adminbhess\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/bhess.jpm.gov.my\/index.php\/category\/aktiviti-2026\/\" rel=\"category tag\">Aktiviti 2026<\/a> <a href=\"https:\/\/bhess.jpm.gov.my\/index.php\/category\/aktiviti-2026\/aktiviti-utama-26\/\" rel=\"category tag\">Aktiviti Utama<\/a>","rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/posts\/5579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/comments?post=5579"}],"version-history":[{"count":1,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/posts\/5579\/revisions"}],"predecessor-version":[{"id":5580,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/posts\/5579\/revisions\/5580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/media\/5572"}],"wp:attachment":[{"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/media?parent=5579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/categories?post=5579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bhess.jpm.gov.my\/index.php\/wp-json\/wp\/v2\/tags?post=5579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}